{"id":141,"date":"2014-01-08T21:58:00","date_gmt":"2014-01-08T20:58:00","guid":{"rendered":"http:\/\/buergerstiftung-woelfersheim.de\/?p=141"},"modified":"2020-01-01T21:59:50","modified_gmt":"2020-01-01T20:59:50","slug":"ein-platz-in-melbach-wird-schoener","status":"publish","type":"post","link":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/2014\/01\/08\/ein-platz-in-melbach-wird-schoener\/","title":{"rendered":"Ein Platz in Melbach wird sch\u00f6ner"},"content":{"rendered":"\n<p>Fuhr man bis vor wenigen Wochen auf dem Steinfurther  Weg durch Melbach, dann blickte man auf einen unansehnlichen Platz, auf  dem ein graues Betonh\u00e4uschen stand, das von B\u00fcschen und B\u00e4umen umgeben  war. Die wenig ansprechende Freifl\u00e4che an der Kreuzung Gro\u00dfe Gasse \/  Steinfurther Weg wurde nun von Grund auf neu gestaltet und kann sich  sehen lassen!<br>Im zur\u00fcckliegenden Jahr wurde mit den Anwohnern ein  Konzept ausgearbeitet, dass optisch ansprechend sein sollte, aber  zugleich sehr pflegeleicht f\u00fcr die Mitarbeiter des Bauhofes. Im ersten  Schritt wurde die vorhandene Trafostation mit Unterst\u00fctzung der  W\u00f6lfersheimer B\u00fcrgerstiftung ansprechender gestaltet. Nach einer  Motivvorlage des Melbacher K\u00fcnstlers Hermann Schleuning spr\u00fchte der  geb\u00fcrtige Melbacher Graffitik\u00fcnstler Viktor Sobek ein Bild der Melbacher  Kirche auf das kleine Bauwerk, das mit weiteren Mustern verziert wurde.  Im n\u00e4chsten Schritt entstand im hinteren Bereich des Platzes eine Mauer  aus Sandstein, die den Platz optisch einfassen soll. Die bestehenden  B\u00fcsche wurden entfernt und die Baumscheiben wurden mit Sandsteinen  abgetrennt. Ebenfalls aus gro\u00dfen Sandsteinstufen entstanden zwei  Pflanzk\u00fcbel, die im Fr\u00fchjahr mit pflegeleichten Stauden und Gr\u00e4sern  bepflanzt werden sollen. Nachdem die Grasnarbe entfernt war, wurde eine  wassergebundene Decke aufgetragen, die optisch zu den verwendeten  Sandsteinen passt. F\u00fcr die sp\u00e4teren B\u00e4nke wurden bereits gro\u00dfe  Sandsteinbl\u00f6cke gesetzt. Zwischen den Bl\u00f6cken sollen im Fr\u00fchjahr  Sitzfl\u00e4chen aus Holz mit einer abst\u00fctzenden R\u00fcckenlehne montiert werden,  auf denen man auf dem Weg zum Friedhof eine kurze Pause einlegen kann.<br>\u201eMit  ein wenig Phantasie kann man es schon erahnen: Der neu gestaltete Platz  ist optisch sehr ansprechend und wird k\u00fcnftig nur einen geringen  Pflegeaufwand verursachen. Ich danke allen, die sich ehrenamtlich an der  Gestaltung beteiligt haben. Besonderen Dank richte ich jedoch an die  Mitarbeiter des Bauhofes, die s\u00e4mtliche Arbeiten selbst durchgef\u00fchrt  haben. Besonders die Verarbeitung der schweren Steine war nicht nur  anstrengend, sondern erforderte auch einiges an Geschickt. Die Arbeit  hat sich aber gelohnt und das Ergebnis kann sich bereits jetzt sehen  lassen.\u201c dankte B\u00fcrgermeister K\u00f6tter seinen Mitarbeitern. \u00a0 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fuhr man bis vor wenigen Wochen auf dem Steinfurther Weg durch Melbach, dann blickte man auf einen unansehnlichen Platz, auf dem ein graues Betonh\u00e4uschen stand, das von B\u00fcschen und B\u00e4umen umgeben war. Die wenig ansprechende Freifl\u00e4che an der Kreuzung Gro\u00dfe Gasse \/ Steinfurther Weg wurde nun von Grund auf neu gestaltet und kann sich sehen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":142,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/posts\/141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/comments?post=141"}],"version-history":[{"count":1,"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/posts\/141\/revisions"}],"predecessor-version":[{"id":143,"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/posts\/141\/revisions\/143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/media\/142"}],"wp:attachment":[{"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/media?parent=141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/categories?post=141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/tags?post=141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}