{"id":144,"date":"2013-10-24T22:00:00","date_gmt":"2013-10-24T20:00:00","guid":{"rendered":"http:\/\/buergerstiftung-woelfersheim.de\/?p=144"},"modified":"2020-01-01T22:01:44","modified_gmt":"2020-01-01T21:01:44","slug":"wasserstern-und-crosstrainer-begeistern","status":"publish","type":"post","link":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/2013\/10\/24\/wasserstern-und-crosstrainer-begeistern\/","title":{"rendered":"Wasserstern und Crosstrainer begeistern"},"content":{"rendered":"\n<p>W\u00e4hrend Marlon auf den gro\u00dfen gelben Knopf dr\u00fcckt,  damit das Wasser l\u00e4uft, k\u00fcmmert sich Sammy darum, dass es auch in die  richtige Wanne flie\u00dft, damit Joschua in der gro\u00dfen Sch\u00fcssel einen  Sandkuchen backen kann. Tristan zeigt w\u00e4hrenddessen B\u00fcrgermeister Rouven  K\u00f6tter was man mit dem neuen Wasserstern auf dem  Mehrgenerationenspielplatz alles machen kann. Die Kinder der Kita  L\u00f6wenzahn waren mit Bollerwagen und belegten Broten ausgestattet zum  W\u00f6lfersheimer See gekommen und den neuen Spielplatz zu testen. Die  Ger\u00e4te wurden vor wenigen Tagen f\u00fcr die Nutzung freigegeben und bieten  etwas f\u00fcr alle Generationen.<br>Das Gel\u00e4nde hat eine Gr\u00f6\u00dfe von ca. 2.500  m\u00b2 und teilt sich in drei Bereiche - einen Sand- und Wasserspielbereich  insbesondere f\u00fcr Kinder unter drei Jahren, einen Bereich mit  Kletterger\u00e4ten f\u00fcr Kinder von 4 bis 12 Jahren und einen  Outdoorfitness-Bereich f\u00fcr alle Gr\u00f6\u00dferen, einschlie\u00dflich der Senioren.  An der Sandfl\u00e4che ist der gro\u00dfe \"Wasserstern\" mit Pumpe und Rohren, eine  Klettergiraffe, ein Karussell und eine Schaukel zu finden. Im  Spielbereich f\u00fcr etwas \u00e4ltere Kinder sind eine gro\u00dfe Kletterkombination  und eine Schaukel installiert. Hier wurde kein Sand, sondern feiner,  runder Kies verwendet, der bessere Eigenschaften bei der Abfederung und  Reinigung bietet als Sand. Im Outdoorfitness-Bereich werden mehrere  Sportger\u00e4te wie eine Situpbank oder ein Crosstrainer geboten, die ein  umfassendes, leichtes Training f\u00fcr den gesamten K\u00f6rper in allen  Altersgruppen erm\u00f6glichen. Rita Rie\u00df, die Vorsitzende des Ausschusses  f\u00fcr Sport, Kultur, Jugend und Soziales und Loni Konietzke, die  Vorsitzende des W\u00f6lfersheimer Seniorenclubs, testeten die neu  installierten Ger\u00e4te und lie\u00dfen sich von Manual Gro\u00df,\u00a0 Tipps zur Nutzung  geben. Gro\u00df ist Inhaber des W\u00f6lfersheimer Fitnessstudios Fitdelio und  unterst\u00fctzte die Gemeinde bei der Auswahl der n\u00f6tigen Ger\u00e4te. Eines der  Fitnessger\u00e4te wurde von der W\u00f6lfersheimer B\u00fcrgerstiftung finanziert.  Geplant wurde der Spielplatz von Fachbereichleiter Markus Klopsch und  f\u00fcr die Realisierung war der Bauhof zust\u00e4ndig. Vollst\u00e4ndig umgesetzt  wurde die Planung noch nicht. Im kommenden Jahr sollen noch B\u00e4ume,  Str\u00e4ucher und B\u00e4nke platziert werden. Die Wege wurden bewusst gro\u00dfz\u00fcgig  angelegt um sp\u00e4ter problemlos weitere Ger\u00e4te installieren zu k\u00f6nnen. <br>\u201eSchon  kurz nach der Freigabe wurden die Ger\u00e4te rege genutzt und nach den  Anpflanzungen im n\u00e4chsten Fr\u00fchjahr wird der Spielplatz auch optisch  ansprechender. Es entsteht damit nicht nur ein Spielplatz f\u00fcr Kinder und  Jugendliche, sondern f\u00fcr Menschen jeden Alters. Am idyllischen Seeufer  wird somit ein Treffpunkt f\u00fcr alle Generationen geschaffen. Mit dem  Mehrgenerationenspielplatz wird der W\u00f6lfersheimer See als  Naherholungsperle f\u00fcr unsere B\u00fcrger noch attraktiver.\u201c so B\u00fcrgermeister  K\u00f6tter. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrend Marlon auf den gro\u00dfen gelben Knopf dr\u00fcckt, damit das Wasser l\u00e4uft, k\u00fcmmert sich Sammy darum, dass es auch in die richtige Wanne flie\u00dft, damit Joschua in der gro\u00dfen Sch\u00fcssel einen Sandkuchen backen kann. Tristan zeigt w\u00e4hrenddessen B\u00fcrgermeister Rouven K\u00f6tter was man mit dem neuen Wasserstern auf dem Mehrgenerationenspielplatz alles machen kann. Die Kinder der [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":145,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/posts\/144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/comments?post=144"}],"version-history":[{"count":1,"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/posts\/144\/revisions"}],"predecessor-version":[{"id":146,"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/posts\/144\/revisions\/146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/media\/145"}],"wp:attachment":[{"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/media?parent=144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/categories?post=144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/buergerstiftung-woelfersheim.de\/index.php\/wp-json\/wp\/v2\/tags?post=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}